{"id":3198,"date":"2022-09-26T17:07:57","date_gmt":"2022-09-26T15:07:57","guid":{"rendered":"https:\/\/giellavahkku.org\/?page_id=3198"},"modified":"2022-09-26T17:07:59","modified_gmt":"2022-09-26T15:07:59","slug":"lasseet-tabahtusad","status":"publish","type":"page","link":"https:\/\/giellavahkku.org\/smn\/lasseet-tabahtusad\/","title":{"rendered":"Lasseet t\u00e1b\u00e1htus\u00e2d"},"content":{"rendered":"<div id=\"event-submission-block_d171e7a2cfca220f1b687f12462aa369\" class=\"wp-block-event-submission\">\t\t\t\t<form id=\"event-submission\" class=\"acf-form\" action=\"\" method=\"post\">\n\t\t\t\t\t<div id=\"acf-form-data\" class=\"acf-hidden\">\n\t\t<input type=\"hidden\" id=\"_acf_screen\" name=\"_acf_screen\" value=\"acf_form\"\/><input type=\"hidden\" id=\"_acf_post_id\" name=\"_acf_post_id\" value=\"new_post\"\/><input type=\"hidden\" id=\"_acf_validation\" name=\"_acf_validation\" value=\"1\"\/><input type=\"hidden\" id=\"_acf_form\" name=\"_acf_form\" value=\"event-submission\"\/><input type=\"hidden\" id=\"_acf_nonce\" name=\"_acf_nonce\" value=\"f072209290\"\/><input type=\"hidden\" id=\"_acf_changed\" name=\"_acf_changed\" value=\"0\"\/><input type=\"hidden\" id=\"_acf_location[post_id]\" name=\"_acf_location[post_id]\" value=\"3198\"\/>\t<\/div>\n\t\t\t\t<div class=\"acf-fields acf-form-fields -top\">\n\t\t\t\t<div class=\"gc-events-submission-form\">\t\t\t\t<div class=\"acf-field acf-field-text acf-field--post-title is-required\" data-name=\"_post_title\" data-type=\"text\" data-key=\"_post_title\" data-required=\"1\">\n<div class=\"acf-label\">\n<label for=\"acf-_post_title\">Paje\u010daal\u00e2 <span class=\"acf-required\">*<\/span><\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap\"><input type=\"text\" id=\"acf-_post_title\" name=\"acf[_post_title]\" required=\"required\"\/><\/div><\/div>\n<\/div>\n<div class=\"acf-field acf-field-date-picker acf-field-1a475dddf573e-1 is-required\" style=\"width:50%;\" data-name=\"date_start\" data-type=\"date_picker\" data-key=\"field_1a475dddf573e_1\" data-required=\"1\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_1a475dddf573e_1\">Alg\u00e2ttempeivimeeri <span class=\"acf-required\">*<\/span><\/label><\/div>\n<div class=\"acf-input\">\n\t\t<div class=\"acf-date-picker acf-input-wrap\" data-date_format=\"dd\/mm\/yy\" data-first_day=\"1\">\n\t\t\t<input type=\"hidden\" id=\"acf-field_1a475dddf573e_1\" name=\"acf[field_1a475dddf573e_1]\" value=\"\"\/>\t\t\t<input type=\"text\" class=\"input\" value=\"\" data-default-to-today=\"0\"\/>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"acf-field acf-field-date-picker acf-field-0e8e5eee4b38e-1\" style=\"width:50%;\" data-name=\"date_end\" data-type=\"date_picker\" data-key=\"field_0e8e5eee4b38e_1\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_0e8e5eee4b38e_1\">Nuuh\u00e2mpeivimeeri<\/label><\/div>\n<div class=\"acf-input\">\n\t\t<div class=\"acf-date-picker acf-input-wrap\" data-date_format=\"dd\/mm\/yy\" data-first_day=\"1\">\n\t\t\t<input type=\"hidden\" id=\"acf-field_0e8e5eee4b38e_1\" name=\"acf[field_0e8e5eee4b38e_1]\" value=\"\"\/>\t\t\t<input type=\"text\" class=\"input\" value=\"\" data-default-to-today=\"0\"\/>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"acf-field acf-field-time-picker acf-field-b01bfa2a3d8fd-1\" style=\"width:50%;\" data-name=\"time_start\" data-type=\"time_picker\" data-key=\"field_b01bfa2a3d8fd_1\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_b01bfa2a3d8fd_1\">Alg\u00e2ttem\u00e4igi<\/label><\/div>\n<div class=\"acf-input\">\n\t\t<div class=\"acf-time-picker acf-input-wrap\" data-time_format=\"HH:mm\">\n\t\t\t<input type=\"hidden\" id=\"acf-field_b01bfa2a3d8fd_1\" class=\"input-alt\" type=\"hidden\" name=\"acf[field_b01bfa2a3d8fd_1]\" value=\"\"\/>\t\t\t<input type=\"text\" class=\"input\" value=\"\"\/>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"acf-field acf-field-time-picker acf-field-816971dddc7a8-1\" style=\"width:50%;\" data-name=\"time_end\" data-type=\"time_picker\" data-key=\"field_816971dddc7a8_1\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_816971dddc7a8_1\">Nuuh\u00e2m\u00e4igi<\/label><\/div>\n<div class=\"acf-input\">\n\t\t<div class=\"acf-time-picker acf-input-wrap\" data-time_format=\"HH:mm\">\n\t\t\t<input type=\"hidden\" id=\"acf-field_816971dddc7a8_1\" class=\"input-alt\" type=\"hidden\" name=\"acf[field_816971dddc7a8_1]\" value=\"\"\/>\t\t\t<input type=\"text\" class=\"input\" value=\"\"\/>\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"acf-field acf-field-select acf-field-62fcce743a8fc\" data-name=\"timezone\" data-type=\"select\" data-key=\"field_62fcce743a8fc\" data-acfe-search-placeholder=\"Search for timezone\">\n<div class=\"acf-label\">\n<label for=\"acf-field_62fcce743a8fc\">\u00c4igistiel\u00e2s<\/label><\/div>\n<div class=\"acf-input\">\n<input type=\"hidden\" id=\"acf-field_62fcce743a8fc-input\" name=\"acf[field_62fcce743a8fc]\"\/><select id=\"acf-field_62fcce743a8fc\" class=\"\" name=\"acf[field_62fcce743a8fc]\" data-ui=\"1\" data-ajax=\"0\" data-multiple=\"0\" data-placeholder=\"Select\" data-allow_null=\"1\"><option value=\"\">&#8211; Select &#8211;<\/option><option value=\"Africa\/Abidjan\">Africa\/Abidjan<\/option><option value=\"Africa\/Accra\">Africa\/Accra<\/option><option value=\"Africa\/Addis_Ababa\">Africa\/Addis Ababa<\/option><option value=\"Africa\/Algiers\">Africa\/Algiers<\/option><option value=\"Africa\/Asmara\">Africa\/Asmara<\/option><option value=\"Africa\/Bamako\">Africa\/Bamako<\/option><option value=\"Africa\/Bangui\">Africa\/Bangui<\/option><option value=\"Africa\/Banjul\">Africa\/Banjul<\/option><option value=\"Africa\/Bissau\">Africa\/Bissau<\/option><option value=\"Africa\/Blantyre\">Africa\/Blantyre<\/option><option value=\"Africa\/Brazzaville\">Africa\/Brazzaville<\/option><option value=\"Africa\/Bujumbura\">Africa\/Bujumbura<\/option><option value=\"Africa\/Cairo\">Africa\/Cairo<\/option><option value=\"Africa\/Casablanca\">Africa\/Casablanca<\/option><option value=\"Africa\/Ceuta\">Africa\/Ceuta<\/option><option value=\"Africa\/Conakry\">Africa\/Conakry<\/option><option value=\"Africa\/Dakar\">Africa\/Dakar<\/option><option value=\"Africa\/Dar_es_Salaam\">Africa\/Dar es Salaam<\/option><option value=\"Africa\/Djibouti\">Africa\/Djibouti<\/option><option value=\"Africa\/Douala\">Africa\/Douala<\/option><option value=\"Africa\/El_Aaiun\">Africa\/El Aaiun<\/option><option value=\"Africa\/Freetown\">Africa\/Freetown<\/option><option value=\"Africa\/Gaborone\">Africa\/Gaborone<\/option><option value=\"Africa\/Harare\">Africa\/Harare<\/option><option value=\"Africa\/Johannesburg\">Africa\/Johannesburg<\/option><option value=\"Africa\/Juba\">Africa\/Juba<\/option><option value=\"Africa\/Kampala\">Africa\/Kampala<\/option><option value=\"Africa\/Khartoum\">Africa\/Khartoum<\/option><option value=\"Africa\/Kigali\">Africa\/Kigali<\/option><option value=\"Africa\/Kinshasa\">Africa\/Kinshasa<\/option><option value=\"Africa\/Lagos\">Africa\/Lagos<\/option><option value=\"Africa\/Libreville\">Africa\/Libreville<\/option><option value=\"Africa\/Lome\">Africa\/Lome<\/option><option value=\"Africa\/Luanda\">Africa\/Luanda<\/option><option value=\"Africa\/Lubumbashi\">Africa\/Lubumbashi<\/option><option value=\"Africa\/Lusaka\">Africa\/Lusaka<\/option><option value=\"Africa\/Malabo\">Africa\/Malabo<\/option><option value=\"Africa\/Maputo\">Africa\/Maputo<\/option><option value=\"Africa\/Maseru\">Africa\/Maseru<\/option><option value=\"Africa\/Mbabane\">Africa\/Mbabane<\/option><option value=\"Africa\/Mogadishu\">Africa\/Mogadishu<\/option><option value=\"Africa\/Monrovia\">Africa\/Monrovia<\/option><option value=\"Africa\/Nairobi\">Africa\/Nairobi<\/option><option value=\"Africa\/Ndjamena\">Africa\/Ndjamena<\/option><option value=\"Africa\/Niamey\">Africa\/Niamey<\/option><option value=\"Africa\/Nouakchott\">Africa\/Nouakchott<\/option><option value=\"Africa\/Ouagadougou\">Africa\/Ouagadougou<\/option><option value=\"Africa\/Porto-Novo\">Africa\/Porto-Novo<\/option><option value=\"Africa\/Sao_Tome\">Africa\/Sao Tome<\/option><option value=\"Africa\/Tripoli\">Africa\/Tripoli<\/option><option value=\"Africa\/Tunis\">Africa\/Tunis<\/option><option value=\"Africa\/Windhoek\">Africa\/Windhoek<\/option><option value=\"America\/Adak\">America\/Adak<\/option><option value=\"America\/Anchorage\">America\/Anchorage<\/option><option value=\"America\/Anguilla\">America\/Anguilla<\/option><option value=\"America\/Antigua\">America\/Antigua<\/option><option value=\"America\/Araguaina\">America\/Araguaina<\/option><option value=\"America\/Argentina\/Buenos_Aires\">America\/Argentina &#8211; Buenos Aires<\/option><option value=\"America\/Argentina\/Catamarca\">America\/Argentina &#8211; Catamarca<\/option><option value=\"America\/Argentina\/Cordoba\">America\/Argentina &#8211; Cordoba<\/option><option value=\"America\/Argentina\/Jujuy\">America\/Argentina &#8211; Jujuy<\/option><option value=\"America\/Argentina\/La_Rioja\">America\/Argentina &#8211; La Rioja<\/option><option value=\"America\/Argentina\/Mendoza\">America\/Argentina &#8211; Mendoza<\/option><option value=\"America\/Argentina\/Rio_Gallegos\">America\/Argentina &#8211; Rio Gallegos<\/option><option value=\"America\/Argentina\/Salta\">America\/Argentina &#8211; Salta<\/option><option value=\"America\/Argentina\/San_Juan\">America\/Argentina &#8211; San Juan<\/option><option value=\"America\/Argentina\/San_Luis\">America\/Argentina &#8211; San Luis<\/option><option value=\"America\/Argentina\/Tucuman\">America\/Argentina &#8211; Tucuman<\/option><option value=\"America\/Argentina\/Ushuaia\">America\/Argentina &#8211; Ushuaia<\/option><option value=\"America\/Aruba\">America\/Aruba<\/option><option value=\"America\/Asuncion\">America\/Asuncion<\/option><option value=\"America\/Atikokan\">America\/Atikokan<\/option><option value=\"America\/Bahia\">America\/Bahia<\/option><option value=\"America\/Bahia_Banderas\">America\/Bahia Banderas<\/option><option value=\"America\/Barbados\">America\/Barbados<\/option><option value=\"America\/Belem\">America\/Belem<\/option><option value=\"America\/Belize\">America\/Belize<\/option><option value=\"America\/Blanc-Sablon\">America\/Blanc-Sablon<\/option><option value=\"America\/Boa_Vista\">America\/Boa Vista<\/option><option value=\"America\/Bogota\">America\/Bogota<\/option><option value=\"America\/Boise\">America\/Boise<\/option><option value=\"America\/Cambridge_Bay\">America\/Cambridge Bay<\/option><option value=\"America\/Campo_Grande\">America\/Campo Grande<\/option><option value=\"America\/Cancun\">America\/Cancun<\/option><option value=\"America\/Caracas\">America\/Caracas<\/option><option value=\"America\/Cayenne\">America\/Cayenne<\/option><option value=\"America\/Cayman\">America\/Cayman<\/option><option value=\"America\/Chicago\">America\/Chicago<\/option><option value=\"America\/Chihuahua\">America\/Chihuahua<\/option><option value=\"America\/Ciudad_Juarez\">America\/Ciudad Juarez<\/option><option value=\"America\/Costa_Rica\">America\/Costa Rica<\/option><option value=\"America\/Creston\">America\/Creston<\/option><option value=\"America\/Cuiaba\">America\/Cuiaba<\/option><option value=\"America\/Curacao\">America\/Curacao<\/option><option value=\"America\/Danmarkshavn\">America\/Danmarkshavn<\/option><option value=\"America\/Dawson\">America\/Dawson<\/option><option value=\"America\/Dawson_Creek\">America\/Dawson Creek<\/option><option value=\"America\/Denver\">America\/Denver<\/option><option value=\"America\/Detroit\">America\/Detroit<\/option><option value=\"America\/Dominica\">America\/Dominica<\/option><option value=\"America\/Edmonton\">America\/Edmonton<\/option><option value=\"America\/Eirunepe\">America\/Eirunepe<\/option><option value=\"America\/El_Salvador\">America\/El Salvador<\/option><option value=\"America\/Fortaleza\">America\/Fortaleza<\/option><option value=\"America\/Fort_Nelson\">America\/Fort Nelson<\/option><option value=\"America\/Glace_Bay\">America\/Glace Bay<\/option><option value=\"America\/Goose_Bay\">America\/Goose Bay<\/option><option value=\"America\/Grand_Turk\">America\/Grand Turk<\/option><option value=\"America\/Grenada\">America\/Grenada<\/option><option value=\"America\/Guadeloupe\">America\/Guadeloupe<\/option><option value=\"America\/Guatemala\">America\/Guatemala<\/option><option value=\"America\/Guayaquil\">America\/Guayaquil<\/option><option value=\"America\/Guyana\">America\/Guyana<\/option><option value=\"America\/Halifax\">America\/Halifax<\/option><option value=\"America\/Havana\">America\/Havana<\/option><option value=\"America\/Hermosillo\">America\/Hermosillo<\/option><option value=\"America\/Indiana\/Indianapolis\">America\/Indiana &#8211; Indianapolis<\/option><option value=\"America\/Indiana\/Knox\">America\/Indiana &#8211; Knox<\/option><option value=\"America\/Indiana\/Marengo\">America\/Indiana &#8211; Marengo<\/option><option value=\"America\/Indiana\/Petersburg\">America\/Indiana &#8211; Petersburg<\/option><option value=\"America\/Indiana\/Tell_City\">America\/Indiana &#8211; Tell City<\/option><option value=\"America\/Indiana\/Vevay\">America\/Indiana &#8211; Vevay<\/option><option value=\"America\/Indiana\/Vincennes\">America\/Indiana &#8211; Vincennes<\/option><option value=\"America\/Indiana\/Winamac\">America\/Indiana &#8211; Winamac<\/option><option value=\"America\/Inuvik\">America\/Inuvik<\/option><option value=\"America\/Iqaluit\">America\/Iqaluit<\/option><option value=\"America\/Jamaica\">America\/Jamaica<\/option><option value=\"America\/Juneau\">America\/Juneau<\/option><option value=\"America\/Kentucky\/Louisville\">America\/Kentucky &#8211; Louisville<\/option><option value=\"America\/Kentucky\/Monticello\">America\/Kentucky &#8211; Monticello<\/option><option value=\"America\/Kralendijk\">America\/Kralendijk<\/option><option value=\"America\/La_Paz\">America\/La Paz<\/option><option value=\"America\/Lima\">America\/Lima<\/option><option value=\"America\/Los_Angeles\">America\/Los Angeles<\/option><option value=\"America\/Lower_Princes\">America\/Lower Princes<\/option><option value=\"America\/Maceio\">America\/Maceio<\/option><option value=\"America\/Managua\">America\/Managua<\/option><option value=\"America\/Manaus\">America\/Manaus<\/option><option value=\"America\/Marigot\">America\/Marigot<\/option><option value=\"America\/Martinique\">America\/Martinique<\/option><option value=\"America\/Matamoros\">America\/Matamoros<\/option><option value=\"America\/Mazatlan\">America\/Mazatlan<\/option><option value=\"America\/Menominee\">America\/Menominee<\/option><option value=\"America\/Merida\">America\/Merida<\/option><option value=\"America\/Metlakatla\">America\/Metlakatla<\/option><option value=\"America\/Mexico_City\">America\/Mexico City<\/option><option value=\"America\/Miquelon\">America\/Miquelon<\/option><option value=\"America\/Moncton\">America\/Moncton<\/option><option value=\"America\/Monterrey\">America\/Monterrey<\/option><option value=\"America\/Montevideo\">America\/Montevideo<\/option><option value=\"America\/Montserrat\">America\/Montserrat<\/option><option value=\"America\/Nassau\">America\/Nassau<\/option><option value=\"America\/New_York\">America\/New York<\/option><option value=\"America\/Nome\">America\/Nome<\/option><option value=\"America\/Noronha\">America\/Noronha<\/option><option value=\"America\/North_Dakota\/Beulah\">America\/North Dakota &#8211; Beulah<\/option><option value=\"America\/North_Dakota\/Center\">America\/North Dakota &#8211; Center<\/option><option value=\"America\/North_Dakota\/New_Salem\">America\/North Dakota &#8211; New Salem<\/option><option value=\"America\/Nuuk\">America\/Nuuk<\/option><option value=\"America\/Ojinaga\">America\/Ojinaga<\/option><option value=\"America\/Panama\">America\/Panama<\/option><option value=\"America\/Paramaribo\">America\/Paramaribo<\/option><option value=\"America\/Phoenix\">America\/Phoenix<\/option><option value=\"America\/Port-au-Prince\">America\/Port-au-Prince<\/option><option value=\"America\/Port_of_Spain\">America\/Port of Spain<\/option><option value=\"America\/Porto_Velho\">America\/Porto Velho<\/option><option value=\"America\/Puerto_Rico\">America\/Puerto Rico<\/option><option value=\"America\/Punta_Arenas\">America\/Punta Arenas<\/option><option value=\"America\/Rankin_Inlet\">America\/Rankin Inlet<\/option><option value=\"America\/Recife\">America\/Recife<\/option><option value=\"America\/Regina\">America\/Regina<\/option><option value=\"America\/Resolute\">America\/Resolute<\/option><option value=\"America\/Rio_Branco\">America\/Rio Branco<\/option><option value=\"America\/Santarem\">America\/Santarem<\/option><option value=\"America\/Santiago\">America\/Santiago<\/option><option value=\"America\/Santo_Domingo\">America\/Santo Domingo<\/option><option value=\"America\/Sao_Paulo\">America\/Sao Paulo<\/option><option value=\"America\/Scoresbysund\">America\/Scoresbysund<\/option><option value=\"America\/Sitka\">America\/Sitka<\/option><option value=\"America\/St_Barthelemy\">America\/St Barthelemy<\/option><option value=\"America\/St_Johns\">America\/St Johns<\/option><option value=\"America\/St_Kitts\">America\/St Kitts<\/option><option value=\"America\/St_Lucia\">America\/St Lucia<\/option><option value=\"America\/St_Thomas\">America\/St Thomas<\/option><option value=\"America\/St_Vincent\">America\/St Vincent<\/option><option value=\"America\/Swift_Current\">America\/Swift Current<\/option><option value=\"America\/Tegucigalpa\">America\/Tegucigalpa<\/option><option value=\"America\/Thule\">America\/Thule<\/option><option value=\"America\/Tijuana\">America\/Tijuana<\/option><option value=\"America\/Toronto\">America\/Toronto<\/option><option value=\"America\/Tortola\">America\/Tortola<\/option><option value=\"America\/Vancouver\">America\/Vancouver<\/option><option value=\"America\/Whitehorse\">America\/Whitehorse<\/option><option value=\"America\/Winnipeg\">America\/Winnipeg<\/option><option value=\"America\/Yakutat\">America\/Yakutat<\/option><option value=\"Antarctica\/Casey\">Antarctica\/Casey<\/option><option value=\"Antarctica\/Davis\">Antarctica\/Davis<\/option><option value=\"Antarctica\/DumontDUrville\">Antarctica\/DumontDUrville<\/option><option value=\"Antarctica\/Macquarie\">Antarctica\/Macquarie<\/option><option value=\"Antarctica\/Mawson\">Antarctica\/Mawson<\/option><option value=\"Antarctica\/McMurdo\">Antarctica\/McMurdo<\/option><option value=\"Antarctica\/Palmer\">Antarctica\/Palmer<\/option><option value=\"Antarctica\/Rothera\">Antarctica\/Rothera<\/option><option value=\"Antarctica\/Syowa\">Antarctica\/Syowa<\/option><option value=\"Antarctica\/Troll\">Antarctica\/Troll<\/option><option value=\"Antarctica\/Vostok\">Antarctica\/Vostok<\/option><option value=\"Arctic\/Longyearbyen\">Arctic\/Longyearbyen<\/option><option value=\"Asia\/Aden\">Asia\/Aden<\/option><option value=\"Asia\/Almaty\">Asia\/Almaty<\/option><option value=\"Asia\/Amman\">Asia\/Amman<\/option><option value=\"Asia\/Anadyr\">Asia\/Anadyr<\/option><option value=\"Asia\/Aqtau\">Asia\/Aqtau<\/option><option value=\"Asia\/Aqtobe\">Asia\/Aqtobe<\/option><option value=\"Asia\/Ashgabat\">Asia\/Ashgabat<\/option><option value=\"Asia\/Atyrau\">Asia\/Atyrau<\/option><option value=\"Asia\/Baghdad\">Asia\/Baghdad<\/option><option value=\"Asia\/Bahrain\">Asia\/Bahrain<\/option><option value=\"Asia\/Baku\">Asia\/Baku<\/option><option value=\"Asia\/Bangkok\">Asia\/Bangkok<\/option><option value=\"Asia\/Barnaul\">Asia\/Barnaul<\/option><option value=\"Asia\/Beirut\">Asia\/Beirut<\/option><option value=\"Asia\/Bishkek\">Asia\/Bishkek<\/option><option value=\"Asia\/Brunei\">Asia\/Brunei<\/option><option value=\"Asia\/Chita\">Asia\/Chita<\/option><option value=\"Asia\/Colombo\">Asia\/Colombo<\/option><option value=\"Asia\/Damascus\">Asia\/Damascus<\/option><option value=\"Asia\/Dhaka\">Asia\/Dhaka<\/option><option value=\"Asia\/Dili\">Asia\/Dili<\/option><option value=\"Asia\/Dubai\">Asia\/Dubai<\/option><option value=\"Asia\/Dushanbe\">Asia\/Dushanbe<\/option><option value=\"Asia\/Famagusta\">Asia\/Famagusta<\/option><option value=\"Asia\/Gaza\">Asia\/Gaza<\/option><option value=\"Asia\/Hebron\">Asia\/Hebron<\/option><option value=\"Asia\/Ho_Chi_Minh\">Asia\/Ho Chi Minh<\/option><option value=\"Asia\/Hong_Kong\">Asia\/Hong Kong<\/option><option value=\"Asia\/Hovd\">Asia\/Hovd<\/option><option value=\"Asia\/Irkutsk\">Asia\/Irkutsk<\/option><option value=\"Asia\/Jakarta\">Asia\/Jakarta<\/option><option value=\"Asia\/Jayapura\">Asia\/Jayapura<\/option><option value=\"Asia\/Jerusalem\">Asia\/Jerusalem<\/option><option value=\"Asia\/Kabul\">Asia\/Kabul<\/option><option value=\"Asia\/Kamchatka\">Asia\/Kamchatka<\/option><option value=\"Asia\/Karachi\">Asia\/Karachi<\/option><option value=\"Asia\/Kathmandu\">Asia\/Kathmandu<\/option><option value=\"Asia\/Khandyga\">Asia\/Khandyga<\/option><option value=\"Asia\/Kolkata\">Asia\/Kolkata<\/option><option value=\"Asia\/Krasnoyarsk\">Asia\/Krasnoyarsk<\/option><option value=\"Asia\/Kuala_Lumpur\">Asia\/Kuala Lumpur<\/option><option value=\"Asia\/Kuching\">Asia\/Kuching<\/option><option value=\"Asia\/Kuwait\">Asia\/Kuwait<\/option><option value=\"Asia\/Macau\">Asia\/Macau<\/option><option value=\"Asia\/Magadan\">Asia\/Magadan<\/option><option value=\"Asia\/Makassar\">Asia\/Makassar<\/option><option value=\"Asia\/Manila\">Asia\/Manila<\/option><option value=\"Asia\/Muscat\">Asia\/Muscat<\/option><option value=\"Asia\/Nicosia\">Asia\/Nicosia<\/option><option value=\"Asia\/Novokuznetsk\">Asia\/Novokuznetsk<\/option><option value=\"Asia\/Novosibirsk\">Asia\/Novosibirsk<\/option><option value=\"Asia\/Omsk\">Asia\/Omsk<\/option><option value=\"Asia\/Oral\">Asia\/Oral<\/option><option value=\"Asia\/Phnom_Penh\">Asia\/Phnom Penh<\/option><option value=\"Asia\/Pontianak\">Asia\/Pontianak<\/option><option value=\"Asia\/Pyongyang\">Asia\/Pyongyang<\/option><option value=\"Asia\/Qatar\">Asia\/Qatar<\/option><option value=\"Asia\/Qostanay\">Asia\/Qostanay<\/option><option value=\"Asia\/Qyzylorda\">Asia\/Qyzylorda<\/option><option value=\"Asia\/Riyadh\">Asia\/Riyadh<\/option><option value=\"Asia\/Sakhalin\">Asia\/Sakhalin<\/option><option value=\"Asia\/Samarkand\">Asia\/Samarkand<\/option><option value=\"Asia\/Seoul\">Asia\/Seoul<\/option><option value=\"Asia\/Shanghai\">Asia\/Shanghai<\/option><option value=\"Asia\/Singapore\">Asia\/Singapore<\/option><option value=\"Asia\/Srednekolymsk\">Asia\/Srednekolymsk<\/option><option value=\"Asia\/Taipei\">Asia\/Taipei<\/option><option value=\"Asia\/Tashkent\">Asia\/Tashkent<\/option><option value=\"Asia\/Tbilisi\">Asia\/Tbilisi<\/option><option value=\"Asia\/Tehran\">Asia\/Tehran<\/option><option value=\"Asia\/Thimphu\">Asia\/Thimphu<\/option><option value=\"Asia\/Tokyo\">Asia\/Tokyo<\/option><option value=\"Asia\/Tomsk\">Asia\/Tomsk<\/option><option value=\"Asia\/Ulaanbaatar\">Asia\/Ulaanbaatar<\/option><option value=\"Asia\/Urumqi\">Asia\/Urumqi<\/option><option value=\"Asia\/Ust-Nera\">Asia\/Ust-Nera<\/option><option value=\"Asia\/Vientiane\">Asia\/Vientiane<\/option><option value=\"Asia\/Vladivostok\">Asia\/Vladivostok<\/option><option value=\"Asia\/Yakutsk\">Asia\/Yakutsk<\/option><option value=\"Asia\/Yangon\">Asia\/Yangon<\/option><option value=\"Asia\/Yekaterinburg\">Asia\/Yekaterinburg<\/option><option value=\"Asia\/Yerevan\">Asia\/Yerevan<\/option><option value=\"Atlantic\/Azores\">Atlantic\/Azores<\/option><option value=\"Atlantic\/Bermuda\">Atlantic\/Bermuda<\/option><option value=\"Atlantic\/Canary\">Atlantic\/Canary<\/option><option value=\"Atlantic\/Cape_Verde\">Atlantic\/Cape Verde<\/option><option value=\"Atlantic\/Faroe\">Atlantic\/Faroe<\/option><option value=\"Atlantic\/Madeira\">Atlantic\/Madeira<\/option><option value=\"Atlantic\/Reykjavik\">Atlantic\/Reykjavik<\/option><option value=\"Atlantic\/South_Georgia\">Atlantic\/South Georgia<\/option><option value=\"Atlantic\/Stanley\">Atlantic\/Stanley<\/option><option value=\"Atlantic\/St_Helena\">Atlantic\/St Helena<\/option><option value=\"Australia\/Adelaide\">Australia\/Adelaide<\/option><option value=\"Australia\/Brisbane\">Australia\/Brisbane<\/option><option value=\"Australia\/Broken_Hill\">Australia\/Broken Hill<\/option><option value=\"Australia\/Darwin\">Australia\/Darwin<\/option><option value=\"Australia\/Eucla\">Australia\/Eucla<\/option><option value=\"Australia\/Hobart\">Australia\/Hobart<\/option><option value=\"Australia\/Lindeman\">Australia\/Lindeman<\/option><option value=\"Australia\/Lord_Howe\">Australia\/Lord Howe<\/option><option value=\"Australia\/Melbourne\">Australia\/Melbourne<\/option><option value=\"Australia\/Perth\">Australia\/Perth<\/option><option value=\"Australia\/Sydney\">Australia\/Sydney<\/option><option value=\"Europe\/Amsterdam\">Europe\/Amsterdam<\/option><option value=\"Europe\/Andorra\">Europe\/Andorra<\/option><option value=\"Europe\/Astrakhan\">Europe\/Astrakhan<\/option><option value=\"Europe\/Athens\">Europe\/Athens<\/option><option value=\"Europe\/Belgrade\">Europe\/Belgrade<\/option><option value=\"Europe\/Berlin\">Europe\/Berlin<\/option><option value=\"Europe\/Bratislava\">Europe\/Bratislava<\/option><option value=\"Europe\/Brussels\">Europe\/Brussels<\/option><option value=\"Europe\/Bucharest\">Europe\/Bucharest<\/option><option value=\"Europe\/Budapest\">Europe\/Budapest<\/option><option value=\"Europe\/Busingen\">Europe\/Busingen<\/option><option value=\"Europe\/Chisinau\">Europe\/Chisinau<\/option><option value=\"Europe\/Copenhagen\">Europe\/Copenhagen<\/option><option value=\"Europe\/Dublin\">Europe\/Dublin<\/option><option value=\"Europe\/Gibraltar\">Europe\/Gibraltar<\/option><option value=\"Europe\/Guernsey\">Europe\/Guernsey<\/option><option value=\"Europe\/Helsinki\">Europe\/Helsinki<\/option><option value=\"Europe\/Isle_of_Man\">Europe\/Isle of Man<\/option><option value=\"Europe\/Istanbul\">Europe\/Istanbul<\/option><option value=\"Europe\/Jersey\">Europe\/Jersey<\/option><option value=\"Europe\/Kaliningrad\">Europe\/Kaliningrad<\/option><option value=\"Europe\/Kirov\">Europe\/Kirov<\/option><option value=\"Europe\/Kyiv\">Europe\/Kyiv<\/option><option value=\"Europe\/Lisbon\">Europe\/Lisbon<\/option><option value=\"Europe\/Ljubljana\">Europe\/Ljubljana<\/option><option value=\"Europe\/London\">Europe\/London<\/option><option value=\"Europe\/Luxembourg\">Europe\/Luxembourg<\/option><option value=\"Europe\/Madrid\">Europe\/Madrid<\/option><option value=\"Europe\/Malta\">Europe\/Malta<\/option><option value=\"Europe\/Mariehamn\">Europe\/Mariehamn<\/option><option value=\"Europe\/Minsk\">Europe\/Minsk<\/option><option value=\"Europe\/Monaco\">Europe\/Monaco<\/option><option value=\"Europe\/Moscow\">Europe\/Moscow<\/option><option value=\"Europe\/Oslo\" selected=\"selected\" data-i=\"0\">Europe\/Oslo<\/option><option value=\"Europe\/Paris\">Europe\/Paris<\/option><option value=\"Europe\/Podgorica\">Europe\/Podgorica<\/option><option value=\"Europe\/Prague\">Europe\/Prague<\/option><option value=\"Europe\/Riga\">Europe\/Riga<\/option><option value=\"Europe\/Rome\">Europe\/Rome<\/option><option value=\"Europe\/Samara\">Europe\/Samara<\/option><option value=\"Europe\/San_Marino\">Europe\/San Marino<\/option><option value=\"Europe\/Sarajevo\">Europe\/Sarajevo<\/option><option value=\"Europe\/Saratov\">Europe\/Saratov<\/option><option value=\"Europe\/Simferopol\">Europe\/Simferopol<\/option><option value=\"Europe\/Skopje\">Europe\/Skopje<\/option><option value=\"Europe\/Sofia\">Europe\/Sofia<\/option><option value=\"Europe\/Stockholm\">Europe\/Stockholm<\/option><option value=\"Europe\/Tallinn\">Europe\/Tallinn<\/option><option value=\"Europe\/Tirane\">Europe\/Tirane<\/option><option value=\"Europe\/Ulyanovsk\">Europe\/Ulyanovsk<\/option><option value=\"Europe\/Vaduz\">Europe\/Vaduz<\/option><option value=\"Europe\/Vatican\">Europe\/Vatican<\/option><option value=\"Europe\/Vienna\">Europe\/Vienna<\/option><option value=\"Europe\/Vilnius\">Europe\/Vilnius<\/option><option value=\"Europe\/Volgograd\">Europe\/Volgograd<\/option><option value=\"Europe\/Warsaw\">Europe\/Warsaw<\/option><option value=\"Europe\/Zagreb\">Europe\/Zagreb<\/option><option value=\"Europe\/Zurich\">Europe\/Zurich<\/option><option value=\"Indian\/Antananarivo\">Indian\/Antananarivo<\/option><option value=\"Indian\/Chagos\">Indian\/Chagos<\/option><option value=\"Indian\/Christmas\">Indian\/Christmas<\/option><option value=\"Indian\/Cocos\">Indian\/Cocos<\/option><option value=\"Indian\/Comoro\">Indian\/Comoro<\/option><option value=\"Indian\/Kerguelen\">Indian\/Kerguelen<\/option><option value=\"Indian\/Mahe\">Indian\/Mahe<\/option><option value=\"Indian\/Maldives\">Indian\/Maldives<\/option><option value=\"Indian\/Mauritius\">Indian\/Mauritius<\/option><option value=\"Indian\/Mayotte\">Indian\/Mayotte<\/option><option value=\"Indian\/Reunion\">Indian\/Reunion<\/option><option value=\"Pacific\/Apia\">Pacific\/Apia<\/option><option value=\"Pacific\/Auckland\">Pacific\/Auckland<\/option><option value=\"Pacific\/Bougainville\">Pacific\/Bougainville<\/option><option value=\"Pacific\/Chatham\">Pacific\/Chatham<\/option><option value=\"Pacific\/Chuuk\">Pacific\/Chuuk<\/option><option value=\"Pacific\/Easter\">Pacific\/Easter<\/option><option value=\"Pacific\/Efate\">Pacific\/Efate<\/option><option value=\"Pacific\/Fakaofo\">Pacific\/Fakaofo<\/option><option value=\"Pacific\/Fiji\">Pacific\/Fiji<\/option><option value=\"Pacific\/Funafuti\">Pacific\/Funafuti<\/option><option value=\"Pacific\/Galapagos\">Pacific\/Galapagos<\/option><option value=\"Pacific\/Gambier\">Pacific\/Gambier<\/option><option value=\"Pacific\/Guadalcanal\">Pacific\/Guadalcanal<\/option><option value=\"Pacific\/Guam\">Pacific\/Guam<\/option><option value=\"Pacific\/Honolulu\">Pacific\/Honolulu<\/option><option value=\"Pacific\/Kanton\">Pacific\/Kanton<\/option><option value=\"Pacific\/Kiritimati\">Pacific\/Kiritimati<\/option><option value=\"Pacific\/Kosrae\">Pacific\/Kosrae<\/option><option value=\"Pacific\/Kwajalein\">Pacific\/Kwajalein<\/option><option value=\"Pacific\/Majuro\">Pacific\/Majuro<\/option><option value=\"Pacific\/Marquesas\">Pacific\/Marquesas<\/option><option value=\"Pacific\/Midway\">Pacific\/Midway<\/option><option value=\"Pacific\/Nauru\">Pacific\/Nauru<\/option><option value=\"Pacific\/Niue\">Pacific\/Niue<\/option><option value=\"Pacific\/Norfolk\">Pacific\/Norfolk<\/option><option value=\"Pacific\/Noumea\">Pacific\/Noumea<\/option><option value=\"Pacific\/Pago_Pago\">Pacific\/Pago Pago<\/option><option value=\"Pacific\/Palau\">Pacific\/Palau<\/option><option value=\"Pacific\/Pitcairn\">Pacific\/Pitcairn<\/option><option value=\"Pacific\/Pohnpei\">Pacific\/Pohnpei<\/option><option value=\"Pacific\/Port_Moresby\">Pacific\/Port Moresby<\/option><option value=\"Pacific\/Rarotonga\">Pacific\/Rarotonga<\/option><option value=\"Pacific\/Saipan\">Pacific\/Saipan<\/option><option value=\"Pacific\/Tahiti\">Pacific\/Tahiti<\/option><option value=\"Pacific\/Tarawa\">Pacific\/Tarawa<\/option><option value=\"Pacific\/Tongatapu\">Pacific\/Tongatapu<\/option><option value=\"Pacific\/Wake\">Pacific\/Wake<\/option><option value=\"Pacific\/Wallis\">Pacific\/Wallis<\/option><\/select><\/div>\n<\/div>\n<div class=\"acf-field acf-field-button-group acf-field-6321b8a60a231\" data-name=\"event_type\" data-type=\"button_group\" data-key=\"field_6321b8a60a231\">\n<div class=\"acf-label\">\n<label id=\"acf-field_6321b8a60a231-label\">T\u00e1b\u00e1htus tijpp\u00e2<\/label><\/div>\n<div class=\"acf-input\">\n<input type=\"hidden\" name=\"acf[field_6321b8a60a231]\"\/><div class=\"acf-button-group\" role=\"radiogroup\" aria-labelledby=\"acf-field_6321b8a60a231-label\"><label class=\"selected\" tabindex=\"0\" role=\"radio\" aria-checked=\"true\"><input type=\"radio\" name=\"acf[field_6321b8a60a231]\" value=\"physical\" checked=\"checked\"\/> Fyysis\u00e2\u0161 t\u00e1b\u00e1htus<\/label><label tabindex=\"-1\" role=\"radio\" aria-checked=\"false\"><input type=\"radio\" name=\"acf[field_6321b8a60a231]\" value=\"online\"\/> Nettit\u00e1b\u00e1htus<\/label><label tabindex=\"-1\" role=\"radio\" aria-checked=\"false\"><input type=\"radio\" name=\"acf[field_6321b8a60a231]\" value=\"both\"\/> Kuohtuuh<\/label><\/div><\/div>\n<\/div>\n<div class=\"acf-field acf-field-text acf-field-632027936cb7f\" data-name=\"address\" data-type=\"text\" data-key=\"field_632027936cb7f\">\n<div class=\"acf-label\">\n<label for=\"acf-field_632027936cb7f\">\u010cujott\u00e2s<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap\"><input type=\"text\" id=\"acf-field_632027936cb7f\" name=\"acf[field_632027936cb7f]\" placeholder=\"Lasseet \u010dujott\u00e2s\"\/><\/div><input type=\"hidden\" name=\"ge_field_63216c4f771e8\" id=\"ge-field_63216c4f771e8\" value=\"0\"><p class=\"description\">Jis t\u00e1b\u00e1htus kalga oinu\u0111 k\u00e1rtt\u00e1\u00e1st, te tun koolgah \u010d\u00e4\u00e4lli\u0111 t\u00e1b\u00e1htus fyysisii \u010dujott\u00e2s.<\/p><\/div>\n<\/div>\n<div class=\"acf-field acf-field-wysiwyg acf-field-de36b491f1f04-1\" data-name=\"info\" data-type=\"wysiwyg\" data-key=\"field_de36b491f1f04_1\" data-acfe-wysiwyg-height=\"300\" data-acfe-wysiwyg-disable-wp-style=\"1\" data-acfe-wysiwyg-disable-resize=\"1\" data-acfe-wysiwyg-remove-path=\"1\" data-acfe-wysiwyg-transparent=\"1\" data-acfe-wysiwyg-merge-toolbar=\"1\">\n<div class=\"acf-label\">\n<label for=\"acf-field_de36b491f1f04_1\">T\u00e1b\u00e1htus vald\u00e2lem<\/label><\/div>\n<div class=\"acf-input\">\n\t\t<div id=\"wp-acf-editor-6a03dbb96e229-wrap\" class=\"acf-editor-wrap wp-core-ui wp-editor-wrap tmce-active\" data-toolbar=\"basic\">\n\t\t\t<div id=\"wp-acf-editor-6a03dbb96e229-editor-tools\" class=\"wp-editor-tools hide-if-no-js\">\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div id=\"wp-acf-editor-6a03dbb96e229-editor-container\" class=\"wp-editor-container\">\n\t\t\t\t\t\t\t\t\t\t<textarea id=\"acf-editor-6a03dbb96e229\" class=\"wp-editor-area\" name=\"acf[field_de36b491f1f04_1]\" style=\"height:300px;\"><\/textarea>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"acf-field acf-field-url acf-field-1af8c2f19e6d1-1\" data-name=\"local_url\" data-type=\"url\" data-key=\"field_1af8c2f19e6d1_1\">\n<div class=\"acf-label\">\n<label for=\"acf-field_1af8c2f19e6d1_1\">Li\u014bkk\u00e2 t\u00e1b\u00e1htusp\u00e1\u00e1ik\u00e1n<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap acf-url\"><i class=\"acf-icon -globe -small\"><\/i><input type=\"url\" id=\"acf-field_1af8c2f19e6d1_1\" name=\"acf[field_1af8c2f19e6d1_1]\" placeholder=\"https:\/\/\"\/><\/div><\/div>\n<\/div>\n<div class=\"acf-field acf-field-text acf-field-744c1e8042e12-1\" style=\"width:50%;\" data-name=\"price\" data-type=\"text\" data-key=\"field_744c1e8042e12_1\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_744c1e8042e12_1\">Hadde<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap\"><input type=\"text\" id=\"acf-field_744c1e8042e12_1\" name=\"acf[field_744c1e8042e12_1]\"\/><\/div><p class=\"description\">Kye\u0111e ku\u00e1rusin jis nuuvt\u00e1<\/p><\/div>\n<\/div>\n<div class=\"acf-field acf-field-select acf-field-62fcf8d623ad5\" style=\"width:50%;\" data-name=\"currency\" data-type=\"select\" data-key=\"field_62fcf8d623ad5\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_62fcf8d623ad5\">Vaaluut<\/label><\/div>\n<div class=\"acf-input\">\n<input type=\"hidden\" id=\"acf-field_62fcf8d623ad5-input\" name=\"acf[field_62fcf8d623ad5]\"\/><select id=\"acf-field_62fcf8d623ad5\" class=\"\" name=\"acf[field_62fcf8d623ad5]\" data-ui=\"1\" data-ajax=\"0\" data-multiple=\"0\" data-placeholder=\"Select\" data-allow_null=\"1\"><option value=\"\" selected=\"selected\" data-i=\"0\">&#8211; Select &#8211;<\/option><option value=\"EUR\">Euro (&euro;)<\/option><option value=\"NOK\">Norwegian krone (&#107;&#114;)<\/option><option value=\"RUB\">Russian ruble (&#8381;)<\/option><option value=\"SEK\">Swedish krona (&#107;&#114;)<\/option><\/select><\/div>\n<\/div>\n<div class=\"acf-field acf-field-true-false acf-field-632990f3cbf69\" data-name=\"has_link\" data-type=\"true_false\" data-key=\"field_632990f3cbf69\">\n<div class=\"acf-label\">\n<label for=\"acf-field_632990f3cbf69\">Li\u014bkk\u00e2 liipui u\u00e1stim\u00e2n?<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-true-false\">\n\t\t\t<input type=\"hidden\" name=\"acf[field_632990f3cbf69]\" value=\"0\"\/>\t<label>\n\t\t<input type=\"checkbox\" id=\"acf-field_632990f3cbf69\" name=\"acf[field_632990f3cbf69]\" value=\"1\" class=\"acf-switch-input\" autocomplete=\"off\"\/>\n\t\t\t<div class=\"acf-switch\"><span class=\"acf-switch-on\">Yes<\/span><span class=\"acf-switch-off\">No<\/span><div class=\"acf-switch-slider\"><\/div><\/div>\t\t\t\t<\/label>\n<\/div>\n\t\t\t<\/div>\n<\/div>\n<div class=\"acf-field acf-field-url acf-field-1287f944eddd0-1 acfe-no-label\" data-name=\"link\" data-type=\"url\" data-key=\"field_1287f944eddd0_1\" data-conditions=\"[[{&quot;field&quot;:&quot;field_632990f3cbf69&quot;,&quot;value&quot;:&quot;1&quot;,&quot;operator&quot;:&quot;==&quot;}]]\">\n<div class=\"acf-label\">\n<\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap acf-url\"><i class=\"acf-icon -globe -small\"><\/i><input type=\"url\" id=\"acf-field_1287f944eddd0_1\" name=\"acf[field_1287f944eddd0_1]\" placeholder=\"https:\/\/\"\/><\/div><\/div>\n<\/div>\n<div class=\"acf-field acf-field-text acf-field-63299d1b06b9f\" style=\"width:50%;\" data-name=\"submitted_by_name\" data-type=\"text\" data-key=\"field_63299d1b06b9f\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_63299d1b06b9f\">Nomm\u00e2<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap\"><input type=\"text\" id=\"acf-field_63299d1b06b9f\" name=\"acf[field_63299d1b06b9f]\"\/><\/div><\/div>\n<\/div>\n<div class=\"acf-field acf-field-email acf-field-63299d3b95d93\" style=\"width:50%;\" data-name=\"submitted_by_email\" data-type=\"email\" data-key=\"field_63299d3b95d93\" data-width=\"50\">\n<div class=\"acf-label\">\n<label for=\"acf-field_63299d3b95d93\">\u0160le\u0111g\u00e2post\u00e2<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap\"><input type=\"email\" id=\"acf-field_63299d3b95d93\" name=\"acf[field_63299d3b95d93]\"\/><\/div><\/div>\n<\/div>\n<div class=\"acf-field acf-field-text acf-field--validate-email\" style=\"display:none !important;\" data-name=\"_validate_email\" data-type=\"text\" data-key=\"_validate_email\">\n<div class=\"acf-label\">\n<label for=\"acf-_validate_email\">Validate Email<\/label><\/div>\n<div class=\"acf-input\">\n<div class=\"acf-input-wrap\"><input type=\"text\" id=\"acf-_validate_email\" name=\"acf[_validate_email]\"\/><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"acf-form-submit\">\n\t\t\t\t\t<input type=\"submit\" class=\"acf-button button button-primary button-large\" value=\"Vuolg\u00e2t\" \/>\t\t\t\t\t<span class=\"acf-spinner\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/form>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3198","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/pages\/3198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/comments?post=3198"}],"version-history":[{"count":1,"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/pages\/3198\/revisions"}],"predecessor-version":[{"id":3201,"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/pages\/3198\/revisions\/3201"}],"wp:attachment":[{"href":"https:\/\/giellavahkku.org\/smn\/wp-json\/wp\/v2\/media?parent=3198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}